{"id":102221,"date":"2023-07-25T14:41:42","date_gmt":"2023-07-25T14:41:42","guid":{"rendered":"https:\/\/primicias2262.com\/noticias\/?p=102221"},"modified":"2023-07-26T13:24:36","modified_gmt":"2023-07-26T13:24:36","slug":"ataque-brutal-de-patovicas-la-justicia-actuo-con-rapidez-y-firmeza-y-eso-es-satisfactorio","status":"publish","type":"post","link":"https:\/\/primicias2262.com\/noticias\/ataque-brutal-de-patovicas-la-justicia-actuo-con-rapidez-y-firmeza-y-eso-es-satisfactorio\/","title":{"rendered":"Ataque brutal de patovicas: \u201cLa Justicia actu\u00f3 con rapidez y firmeza, y eso es satisfactorio\u201d"},"content":{"rendered":"<p><strong>As\u00ed lo destac\u00f3 el secretario de Gobierno Jorge Mart\u00ednez, quien durante el lunes hab\u00eda se\u00f1alado que el caso pasaba directamente a la esfera judicial y en ese aspecto se mostr\u00f3 gratamente sorprendido este martes por la rapidez de la actuaci\u00f3n de la Justicia.<\/strong><\/p>\n<p>En la ma\u00f1ana de \u201cVoces de la Ciudad\u201d, durante una nota telef\u00f3nica realizada por el periodista Jorge G\u00f3mez, el secretario de Gobierno describi\u00f3 cronol\u00f3gicamente todo lo actuado por la Municipalidad desde que se registr\u00f3 la repudiable agresi\u00f3n de los guardias de seguridad del boliche balneario Tom Jones a un par de vecinos.<\/p>\n<p>\u201cA partir de que tomamos conocimiento del brutal ataque, inmediatamente tomamos intervenci\u00f3n y pusimos a disposici\u00f3n de las autoridades policiales, primeramente arrancaron actuaciones de oficio y ya despu\u00e9s en comunicaciones con el abogado de la v\u00edctima sab\u00edamos que por la tarde se iban a hacer presente en la Comisar\u00eda para hacer la denuncia, y ah\u00ed arranc\u00f3 toda la investigaci\u00f3n que termin\u00f3 con la detenci\u00f3n de los tres patovicas\u201d.<\/p>\n<p>Mientras tanto prosigui\u00f3 el funcionario, \u201cnosotros procedimos a la clausura de Tom Jones por tiempo indeterminado y se hizo un requerimiento administrativo de documentaci\u00f3n ampliando el requerimiento que ya hab\u00edamos hecho una semana atr\u00e1s cuando hicimos procedimientos de nocturnidad\u201d.<\/p>\n<p>Y si de la clausura se trata, acerca de las suspicacias de la gente sobre que Tom Jones se va a habilitar enseguida, manifest\u00f3 que \u201ces la segunda vez que me toca clausurar ese lugar y a m\u00ed no me ha pasado nada, ya hab\u00edamos clausurado dos bares la semana anterior, los inspectores de nocturnidad ya tienen una trayectoria trabajando, y c\u00f3mo viene la mano no s\u00e9 si va a hacer solo por un par de d\u00eda la clausura sino varios\u201d.<\/p>\n<p>Argument\u00f3 en ese sentido que \u201cla Municipalidad no es el \u00fanico organismo que va a intervenir, sabemos que ha habido llamados de organismos nacionales relacionados a la seguridad privada que tambi\u00e9n van a tomar intervenci\u00f3n en el asunto, y hay que ver el trabajo de la Provincia con relevamientos en el lugar en cuanto al registro\u2026 hay muchos organismos que nos llamaron el lunes interesados en el tema y \u00a0seguramente van a recaer sobre el lugar para realizar alguna inspecci\u00f3n y requerirle documentaci\u00f3n a la empresa, as\u00ed que dudo que en el corto plazo haya novedades con la reapertura de la boliche\u201d.<\/p>\n<p>Defini\u00e9ndose \u201cconmovido por lo que pas\u00f3\u201d, Mart\u00ednez a su vez subray\u00f3 que estaba satisfecho \u201ccon la r\u00e1pida respuesta y firme de la Justicia\u2026 no s\u00e9 si todo el mundo esperaba una detenci\u00f3n con un agravante de la imputaci\u00f3n hacia estas personas, pero es satisfactorio en cuanto a la firmeza con que ha actuado la Justicia. La verdad es que se actu\u00f3 con rapidez y firmeza, y tomamos esa decisi\u00f3n de forma satisfactoria porque tienen que pagar las consecuencias de sus actos\u201d.<\/p>\n<p>Finalmente, el secretario de Gobierno agreg\u00f3 un p\u00e1rrafo dedicado a la intensa madrugada del domingo en la villa balnearia: \u201cHay mucha confusi\u00f3n por si estaba o no la polic\u00eda en Tom Jones, pero la realidad es que en ese momento se produjeron varios incidentes, por lo tanto el domo de monitoreo estaba mirando a la polic\u00eda que estaba a 100 metros de ah\u00ed, es decir en en 85 precisamente en el pub y bar \u201cMy Life\u201d, donde hab\u00eda disturbios y corridas, ya que todo fue en el momento del cierre de los boliches\u201d.<\/p>\n<p>\u201cEn ese lugar se encontraba el Comando de Patrullas y el GAD, mientras que hay c\u00e1maras fijas mirando hacia el lado de Tom Jones pero se ven escaramuzas a la distancia, no particularmente todo lo que vimos despu\u00e9s, que fue aportado a la Justicia y el fiscal har\u00e1 toda la evaluaci\u00f3n, pero las c\u00e1maras nuestras estaban posadas en \u201cMy Life\u201d porque fue antes de lo de Tom Jones, aunque todos los hechos se produjeron en unos 15 minutos\u201d, culmin\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed lo destac\u00f3 el secretario de Gobierno Jorge Mart\u00ednez, quien durante el lunes hab\u00eda se\u00f1alado que el caso pasaba directamente a la esfera judicial y en ese aspecto se mostr\u00f3 gratamente sorprendido este martes por la rapidez de la actuaci\u00f3n de la Justicia. En la ma\u00f1ana de \u201cVoces de la Ciudad\u201d, durante una nota telef\u00f3nica [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":102222,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-102221","post","type-post","status-publish","format-standard","has-post-thumbnail","category-masnoticias"],"_links":{"self":[{"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/posts\/102221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/comments?post=102221"}],"version-history":[{"count":2,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/posts\/102221\/revisions"}],"predecessor-version":[{"id":102261,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/posts\/102221\/revisions\/102261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/media\/102222"}],"wp:attachment":[{"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/media?parent=102221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/categories?post=102221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/tags?post=102221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}