{"id":90506,"date":"2022-06-06T11:44:38","date_gmt":"2022-06-06T14:44:38","guid":{"rendered":"https:\/\/primicias2262.com\/?p=90506"},"modified":"2022-06-06T11:44:38","modified_gmt":"2022-06-06T14:44:38","slug":"futbol-local-show-de-goles-estadisticas-y-proxima-fecha","status":"publish","type":"post","link":"https:\/\/primicias2262.com\/noticias\/futbol-local-show-de-goles-estadisticas-y-proxima-fecha\/","title":{"rendered":"F\u00fatbol local: show de goles, estad\u00edsticas y pr\u00f3xima fecha"},"content":{"rendered":"<p>La 10ma fecha del f\u00fatbol local, Torneo \u00abEmilio Jeder Resuene\u00bb de la Liga Necochea de F\u00fatbol, se jug\u00f3 de manera parcial por la suspensi\u00f3n de Defensores de Juan N. Fern\u00e1ndez frente a Estaci\u00f3n Quequ\u00e9n, pero a\u00fan as\u00ed tiene un alto registro de goles: se convirtieron 21 tantos y a continuaci\u00f3n se puede mirar el show editado por Sporting Carina.<\/p>\n<p><strong>Show de goles &#8211; 10ma fecha<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"LNF 2022 - FECHA 10 - SHOW DE GOLES\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/sORsgBIS8FU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><strong>Posiciones:<\/strong><\/p>\n<table width=\"463\">\n<tbody>\n<tr>\n<td colspan=\"9\"><strong>ZONA A<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>POS<\/strong><\/td>\n<td><strong>EQUIPOS<\/strong><\/td>\n<td><strong>J<\/strong><\/td>\n<td><strong>G<\/strong><\/td>\n<td><strong>E<\/strong><\/td>\n<td><strong>P<\/strong><\/td>\n<td><strong>GF<\/strong><\/td>\n<td><strong>GC<\/strong><\/td>\n<td><strong>PTS<\/strong><\/td>\n<\/tr>\n<tr>\n<td>1<\/td>\n<td>Independiente (SC)<\/td>\n<td>9<\/td>\n<td>8<\/td>\n<td>0<\/td>\n<td>1<\/td>\n<td>28<\/td>\n<td>3<\/td>\n<td>24<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td>Sportivo (SC)<\/td>\n<td>9<\/td>\n<td>7<\/td>\n<td>1<\/td>\n<td>1<\/td>\n<td>28<\/td>\n<td>8<\/td>\n<td>22<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td>Villa D\u00edaz V\u00e9lez<\/td>\n<td>9<\/td>\n<td>6<\/td>\n<td>1<\/td>\n<td>2<\/td>\n<td>19<\/td>\n<td>7<\/td>\n<td>19<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td>Jorge Newbery<\/td>\n<td>9<\/td>\n<td>4<\/td>\n<td>3<\/td>\n<td>2<\/td>\n<td>16<\/td>\n<td>15<\/td>\n<td>15<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td>Rivadavia<\/td>\n<td>8<\/td>\n<td>4<\/td>\n<td>2<\/td>\n<td>2<\/td>\n<td>14<\/td>\n<td>10<\/td>\n<td>14<\/td>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td>Mataderos<\/td>\n<td>9<\/td>\n<td>3<\/td>\n<td>2<\/td>\n<td>4<\/td>\n<td>13<\/td>\n<td>15<\/td>\n<td>11<\/td>\n<\/tr>\n<tr>\n<td>7<\/td>\n<td>Ministerio<\/td>\n<td>9<\/td>\n<td>2<\/td>\n<td>3<\/td>\n<td>4<\/td>\n<td>8<\/td>\n<td>13<\/td>\n<td>9<\/td>\n<\/tr>\n<tr>\n<td>8<\/td>\n<td>Independiente (L)<\/td>\n<td>9<\/td>\n<td>2<\/td>\n<td>1<\/td>\n<td>6<\/td>\n<td>7<\/td>\n<td>12<\/td>\n<td>7<\/td>\n<\/tr>\n<tr>\n<td colspan=\"9\"><strong>ZONA B<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>POS<\/strong><\/td>\n<td><strong>EQUIPOS<\/strong><\/td>\n<td><strong>J<\/strong><\/td>\n<td><strong>G<\/strong><\/td>\n<td><strong>E<\/strong><\/td>\n<td><strong>P<\/strong><\/td>\n<td><strong>GF<\/strong><\/td>\n<td><strong>GC<\/strong><\/td>\n<td><strong>PTS<\/strong><\/td>\n<\/tr>\n<tr>\n<td>1<\/td>\n<td>Del Valle<\/td>\n<td>10<\/td>\n<td>6<\/td>\n<td>1<\/td>\n<td>3<\/td>\n<td>17<\/td>\n<td>8<\/td>\n<td>19<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td>Gimnasia y Esgrima<\/td>\n<td>10<\/td>\n<td>5<\/td>\n<td>2<\/td>\n<td>3<\/td>\n<td>13<\/td>\n<td>12<\/td>\n<td>17<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td>Estaci\u00f3n Quequ\u00e9n<\/td>\n<td>8<\/td>\n<td>5<\/td>\n<td>0<\/td>\n<td>3<\/td>\n<td>13<\/td>\n<td>13<\/td>\n<td>15<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td>Hurac\u00e1n<\/td>\n<td>10<\/td>\n<td>2<\/td>\n<td>2<\/td>\n<td>6<\/td>\n<td>7<\/td>\n<td>21<\/td>\n<td>8<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td>Nicanor Olivera<\/td>\n<td>9<\/td>\n<td>1<\/td>\n<td>4<\/td>\n<td>4<\/td>\n<td>4<\/td>\n<td>12<\/td>\n<td>7<\/td>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td>Villa del Parque<\/td>\n<td>9<\/td>\n<td>1<\/td>\n<td>2<\/td>\n<td>6<\/td>\n<td>8<\/td>\n<td>19<\/td>\n<td>5<\/td>\n<\/tr>\n<tr>\n<td>7<\/td>\n<td>Defensores (JNF)<\/td>\n<td>9<\/td>\n<td>0<\/td>\n<td>0<\/td>\n<td>9<\/td>\n<td>5<\/td>\n<td>32<\/td>\n<td>0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Pr\u00f3xima fecha &#8211; 11ra (3ra zona campeonato)<\/strong><\/p>\n<p>Sportivo SC vs. Ministerio<br \/>\nMataderos vs. Independiente Lober\u00eda<br \/>\nRivadavia vs. Villa D\u00edaz V\u00e9lez<br \/>\nJorge Newbery vs. Independiente SC<br \/>\nEstaci\u00f3n Quequ\u00e9n vs. Del Valle<br \/>\nHurac\u00e1n vs. Gimnasia<br \/>\nVilla del Parque vs. Nicanor Olivera<\/p>\n<p>Libre: Defensores JNF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 10ma fecha del f\u00fatbol local, Torneo \u00abEmilio Jeder Resuene\u00bb de la Liga Necochea de F\u00fatbol, se jug\u00f3 de manera parcial por la suspensi\u00f3n de Defensores de Juan N. Fern\u00e1ndez frente a Estaci\u00f3n Quequ\u00e9n, pero a\u00fan as\u00ed tiene un alto registro de goles: se convirtieron 21 tantos y a continuaci\u00f3n se puede mirar el show [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":90507,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-90506","post","type-post","status-publish","format-standard","has-post-thumbnail","category-masnoticias"],"_links":{"self":[{"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/posts\/90506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/comments?post=90506"}],"version-history":[{"count":0,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/posts\/90506\/revisions"}],"wp:attachment":[{"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/media?parent=90506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/categories?post=90506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primicias2262.com\/noticias\/wp-json\/wp\/v2\/tags?post=90506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}